{"id":51,"date":"2025-04-14T15:17:01","date_gmt":"2025-04-14T14:17:01","guid":{"rendered":"https:\/\/westleygroup.co.uk\/meighs-westley\/safety-critical-equipment\/"},"modified":"2025-08-29T09:36:12","modified_gmt":"2025-08-29T08:36:12","slug":"safety-critical-equipment","status":"publish","type":"page","link":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/","title":{"rendered":"Safety Critical Equipment"},"content":{"rendered":"<section id=\"armstrong-block-page-heading-block_e8717b5b1a7ab67304652a3599bd28a6\" class=\"page-heading\" >\n            <div class=\"image-container\">\n            <img decoding=\"async\"\n                src=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-content\/uploads\/sites\/2\/2025\/04\/HS2A3449-WEB-1536x578-1.webp\"\n                alt=\"\"\n                srcset=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-content\/uploads\/sites\/2\/2025\/04\/HS2A3449-WEB-1536x578-1.webp 1536w, https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-content\/uploads\/sites\/2\/2025\/04\/HS2A3449-WEB-1536x578-1-300x113.webp 300w, https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-content\/uploads\/sites\/2\/2025\/04\/HS2A3449-WEB-1536x578-1-1024x385.webp 1024w, https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-content\/uploads\/sites\/2\/2025\/04\/HS2A3449-WEB-1536x578-1-768x289.webp 768w\"\n                sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\n            <div class=\"image-overlay\" style=\"background-color: rgba(112,112,112,0.3);\"><\/div>\n\n            <div class=\"page-heading__title\">\n                <div class=\"container-fluid \">\n\n                    <div class=\"row\">\n                        <div class=\"col-lg-12 my-auto\">\n                                                                                        <div class=\"title\">\n                                    <h1 class=\"html-title \">Safety Critical Equipment<\/h1>                                <\/div>\n                            \n\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n\n        <\/div>\n    <\/section>\n\n<section id=\"armstrong-block-sub-pages-panel-block_d6701abe295e08d8042875b07d9a6ed3\" class=\"armstrong-block-sub-pages-panel\" >\n    <div class=\"container-fluid\">\n        <div class=\"row\">\n            <div class=\"col-lg-3\">\n                <div class=\"armstrong-block-sub-pages-panel__menu-wrapper\">\n                    <nav class=\"menu-products-and-services-container\"><ul id=\"menu-products-and-services\" class=\"acf-custom-menu\"><li id=\"menu-item-339\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-339\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/products-services\/\">Products &amp; Services<\/a><\/li>\n<li id=\"menu-item-345\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-345\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/\">Safety Critical Equipment<\/a><\/li>\n<li id=\"menu-item-348\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-348\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/valves\/\">Valves<\/a><\/li>\n<li id=\"menu-item-344\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-344\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/pumps\/\">Pumps<\/a><\/li>\n<li id=\"menu-item-343\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-343\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/propulsion-naval-and-marine\/\">Propulsion \u2013 Naval and Marine<\/a><\/li>\n<li id=\"menu-item-347\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-347\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/seal-components\/\">Seal Components<\/a><\/li>\n<li id=\"menu-item-346\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-346\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/sculptured-art-pieces\/\">Sculptured Art Pieces<\/a><\/li>\n<li id=\"menu-item-342\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-342\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/commercial-net-shapes\/\">Commercial Net Shapes<\/a><\/li>\n<li id=\"menu-item-340\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-340\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/architectural-components\/\">Architectural Components<\/a><\/li>\n<li id=\"menu-item-341\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-341\"><a href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/bells\/\">Bells<\/a><\/li>\n<\/ul><\/nav>                                            <div class=\"red-cta-wrapper\">\n                            <p>To find out more about any of the products or services contact us today<\/p>\n                            <a class=\"blue-hover\" href=\"\/meighs-westleys\/contact-us\/\" target=\"\">\n                                contact us                            <\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n            <div class=\"col-lg-8 offset-lg-1\">\n                <div class=\"armstrong-block-sub-pages-panel__content-wrapper\">\n                                                                                                        <div class=\"standard-content panel-item hide-border\">\n                                                                        <div class=\"\">\n                                        <div class=\"content-container \">\n                                            <p>Meighs &#038; Westleys supports Spunalloys with the strategic requirement for Class 1 components for the UK\u2019s naval programme. Most of these components are pressure containing, flow related components, that are specified to prevent aggressive seawater corrosion such as the primary and return end heat exchange headers for the main condensing system of the nuclear reactor. Produced to net shape using a static sand casting process, a proprietary alloy and running system eliminate selective phase corrosion of previous bronze components.<\/p>\n<p>The complex internal waterway shaping requires robust mould construction, with clever locations to still utilise the proprietary \u2019tilt\/pour\u2019 durville process, preventing turbulence during the filling of the mould and eliminating oxide entrainment. Intensive NDE including 100% radiography is used to prove the integrity of these weld-free, sub-safe, critical components prior to finish machining, assembly and pressure testing.<\/p>\n                                        <\/div>\n                                    <\/div>\n                                                                    <\/div>\n                            \n                            \n                            \n                            \n                            \n                            \n                                                                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":15,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-51","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Safety Critical Equipment - Meighs &amp; Westleys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Safety Critical Equipment - Meighs &amp; Westleys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/\" \/>\n<meta property=\"og:site_name\" content=\"Meighs &amp; Westleys\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T08:36:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/safety-critical-equipment\\\/\",\"url\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/safety-critical-equipment\\\/\",\"name\":\"Safety Critical Equipment - Meighs &amp; Westleys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/#website\"},\"datePublished\":\"2025-04-14T14:17:01+00:00\",\"dateModified\":\"2025-08-29T08:36:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/safety-critical-equipment\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/safety-critical-equipment\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/safety-critical-equipment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products &amp; Services\",\"item\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/products-services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Safety Critical Equipment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/#website\",\"url\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/\",\"name\":\"Meighs & Westleys\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/westleygroup.co.uk\\\/meighs-westleys\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Safety Critical Equipment - Meighs &amp; Westleys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/","og_locale":"en_GB","og_type":"article","og_title":"Safety Critical Equipment - Meighs &amp; Westleys","og_url":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/","og_site_name":"Meighs &amp; Westleys","article_modified_time":"2025-08-29T08:36:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/","url":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/","name":"Safety Critical Equipment - Meighs &amp; Westleys","isPartOf":{"@id":"https:\/\/westleygroup.co.uk\/meighs-westleys\/#website"},"datePublished":"2025-04-14T14:17:01+00:00","dateModified":"2025-08-29T08:36:12+00:00","breadcrumb":{"@id":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/westleygroup.co.uk\/meighs-westleys\/safety-critical-equipment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/westleygroup.co.uk\/meighs-westleys\/"},{"@type":"ListItem","position":2,"name":"Products &amp; Services","item":"https:\/\/westleygroup.co.uk\/meighs-westleys\/products-services\/"},{"@type":"ListItem","position":3,"name":"Safety Critical Equipment"}]},{"@type":"WebSite","@id":"https:\/\/westleygroup.co.uk\/meighs-westleys\/#website","url":"https:\/\/westleygroup.co.uk\/meighs-westleys\/","name":"Meighs & Westleys","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/westleygroup.co.uk\/meighs-westleys\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/pages\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":7,"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/pages\/51\/revisions"}],"predecessor-version":[{"id":540,"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/pages\/51\/revisions\/540"}],"up":[{"embeddable":true,"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/pages\/15"}],"wp:attachment":[{"href":"https:\/\/westleygroup.co.uk\/meighs-westleys\/wp-json\/wp\/v2\/media?parent=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}